{"id":537,"date":"2018-05-07T09:48:09","date_gmt":"2018-05-07T12:48:09","guid":{"rendered":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/?p=537"},"modified":"2018-05-07T10:01:15","modified_gmt":"2018-05-07T13:01:15","slug":"conceptos-basicos-sobre-gamificacion","status":"publish","type":"post","link":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/conceptos-basicos-sobre-gamificacion\/","title":{"rendered":"Conceptos b\u00e1sicos sobre Gamificaci\u00f3n"},"content":{"rendered":"<p>Aunque llevamos tiempo viendo c\u00f3mo este t\u00e9rmino cada vez tiene mayor cabida en\u00a0<strong>e-learning<\/strong>, es posible que a\u00fan no hayas o\u00eddo hablar de \u00e9l. Si es as\u00ed \u00a1tienes que leer este post!<\/p>\n<p>La\u00a0<strong>gamificaci\u00f3n\u00a0<\/strong>(m\u00e1s conocida c\u00f3mo ludificaci\u00f3n) es un t\u00e9rmino no muy antiguo, el cual, nace alrededor del a\u00f1o 2008. Una definici\u00f3n simple ser\u00eda:<\/p>\n<blockquote><p>La gamificaci\u00f3n es el empleo de mec\u00e1nicas de juego en actividades no recreativas con el fin de potenciar actitudes o valores relacionados con el juego.<\/p><\/blockquote>\n<p><strong>Las\u00a0<\/strong><strong>mec\u00e1nicas del juego<\/strong>, son las reglas de la actividad a realizar, consiguen que la participaci\u00f3n en dicha actividad sea divertida y amena. Encontramos dentro de este apartado:<\/p>\n<ul>\n<li>Ganar puntos.<\/li>\n<li>Niveles.<\/li>\n<li>Premios.<\/li>\n<li>Clasificaciones.<\/li>\n<li>Misiones.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Las din\u00e1micas del juego<\/strong>, son los valores que nos impulsan a seguir jugando. Al final del juego conseguiremos asimilar las actitudes o valores que se a\u00f1adieron a la actividad.<\/p>\n<ul>\n<li>Recompensas.<\/li>\n<li>Reconocimiento o prestigio.<\/li>\n<li>Altruismo.<\/li>\n<li>Competici\u00f3n.<\/li>\n<li>Juego Cooperativo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Elementos del juego,\u00a0<\/strong>son complementos que se a\u00f1aden a la actividad.<\/p>\n<ul>\n<li>Avatares.<\/li>\n<li>Puntos acumulados.<\/li>\n<li>Tablero.<\/li>\n<li>Insignias.<\/li>\n<li>Medallas.<\/li>\n<li>El status social entre jugadores.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>\u00bfTe animas a aplicar este concepto tan interesante a tus cursos?<\/p>\n<div class=\"addtoany_share_save_container addtoany_content addtoany_content_bottom\">\n<div class=\"a2a_kit a2a_kit_size_32 addtoany_list\" data-a2a-url=\"https:\/\/www.educativa.com\/soporte-articulos\/sabes-que-es-la-gamificacion-te-damos-unos-conceptos-basicos\/\" data-a2a-title=\"\u00bfSabes qu\u00e9 es la Gamificaci\u00f3n? \u00a1Te damos unos conceptos b\u00e1sicos!\"><a class=\"a2a_button_facebook\" title=\"Facebook\" href=\"https:\/\/www.educativa.com\/#facebook\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"a2a_label\">Facebook<\/span><\/a><a class=\"a2a_button_twitter\" title=\"Twitter\" href=\"https:\/\/www.educativa.com\/#twitter\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"a2a_label\">Twitter<\/span><\/a><a class=\"a2a_button_linkedin\" title=\"LinkedIn\" href=\"https:\/\/www.educativa.com\/#linkedin\" target=\"_blank\" rel=\"nofollow noopener\"><span class=\"a2a_label\">LinkedIn<\/span><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque llevamos tiempo viendo c\u00f3mo este t\u00e9rmino cada vez tiene mayor cabida en\u00a0e-learning, es posible que a\u00fan no hayas o\u00eddo hablar de \u00e9l. Si es as\u00ed \u00a1tienes que leer este post! La\u00a0gamificaci\u00f3n\u00a0(m\u00e1s conocida c\u00f3mo ludificaci\u00f3n) es un t\u00e9rmino no muy antiguo, el cual, nace alrededor del a\u00f1o 2008. Una definici\u00f3n simple ser\u00eda: La gamificaci\u00f3n es &#8230; <a title=\"Conceptos b\u00e1sicos sobre Gamificaci\u00f3n\" class=\"read-more\" href=\"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/conceptos-basicos-sobre-gamificacion\/\" aria-label=\"M\u00e1s en Conceptos b\u00e1sicos sobre Gamificaci\u00f3n\">[+]<\/a><\/p>\n","protected":false},"author":1,"featured_media":551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/posts\/537"}],"collection":[{"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":1,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"predecessor-version":[{"id":538,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/posts\/537\/revisions\/538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/media\/551"}],"wp:attachment":[{"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escuela.deb12-tecno.educativa.com\/sitio\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}